{"id":238427,"date":"2019-05-20T23:18:42","date_gmt":"2019-05-20T20:18:42","guid":{"rendered":"https:\/\/basilica.ro\/?p=238427"},"modified":"2019-05-21T07:41:20","modified_gmt":"2019-05-21T04:41:20","slug":"orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation","status":"publish","type":"post","link":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/","title":{"rendered":"Orthodox media representatives meet in Cyprus to strengthen international cooperation"},"content":{"rendered":"<p><strong>Different representatives of Orthodox media outlets gathered in Cyprus from May 15 to May 19, 2019, to find ways of strengthening the international cooperation between Orthodox media specialists.<\/strong><\/p>\n<p>The meeting was occasioned by the <a href=\"https:\/\/basilica.ro\/en\/orthodoxy-in-colours-photography-exhibition-juxtaposes-cyprus-and-poland\/\">opening of the \u2018Colours of Orthodoxy. Cyprus &#8211; Poland\u2019 Exhibition<\/a> organized by the OrthPhoto.net photography website, the Archdiocese of Cyprus, the Cyprus Photographic Society, and the Publishing House of the Orthodox Metropolis of Warsaw.<\/p>\n<p>Incentivized by the desire to improve their activity at local level and to facilitate cooperation at international level, the Orthodox media representatives had the occasion to visit various holy places of Cyprus and to meet with hierarchs of the Church of Cyprus who are developing inter-Orthodox projects including Metropolitan Chrysostomos of Kition, Metropolitan Isaias of Tamassos, Metropolitan Athanasios of Limassol, and Bishop Epiphanius of Ledra, abbot of Machairas Monastery.<\/p>\n<p>The representatives included the following:<\/p>\n<ul>\n<li>Aleksander Wasyluk, coordinator of <a href=\"https:\/\/www.orthphoto.net\/\">OrthPhoto.net<\/a> (Poland)<\/li>\n<li>Jakob Oniszczuk, coordinator of <a href=\"http:\/\/www.cerkiew.pl\/\">Cerkiew.pl<\/a> (Poland)<\/li>\n<li>Nikos Gouraros, director of <a href=\"https:\/\/pemptousia.com\/\">Pemptousia<\/a>, President of the International Association of Digital media and Orthodoxal Pastoral Care <a href=\"http:\/\/dmopc.org\/\">DMOPC<\/a> (Greece)<\/li>\n<li>Denis Makhanko, regional director of <a href=\"https:\/\/radiovera.ru\/\">Radio Vera<\/a> (Russia)<\/li>\n<li>Aurelian Iftimiu, director of Basilica News Agency of the Romanian Patriarchate (Romania)<\/li>\n<li>Deacon Spiro Topanxha (<a href=\"http:\/\/orthodoxalbania.org\/\">Albania<\/a>)<\/li>\n<li>Ralitsa Kratseva, <a href=\"https:\/\/www.birdhousesofia.com\/\">Birdhouse Sofia<\/a> (Bulgaria)<\/li>\n<li>Artem Makhakaev, East European Bureau of <a href=\"https:\/\/tv-soyuz.ru\/\">Soyuz TV<\/a> station (Belarus)<\/li>\n<\/ul>\n<p>Among the main purposes of the event were sharing experience, moving forward from ideas to projects, better understanding each other\u2019s activity, understanding how Orthodox media outlets can collaborate to promote holy places in different countries on the example of Cyprus, and to identify ways of supporting one another.<\/p>\n<p>Given the fact that the Orthodox media representatives have already developed partnerships and cooperation on certain projects, they expressed their intention to organize similar meetings in the future and expand the network of Orthodox experts.<\/p>\n<p>The participants stressed the importance of existing organizations like\u00a0the International Association of Digital Media and Orthodoxal Pastoral Care (DMOPC) and encourage similar endeavours that will help to establish a network between Orthodox believers around the world.<\/p>\n<p>The meeting was funded by the Deputy Ministry of Tourism in Cyprus.<\/p>\n<div id='gallery-1' class='gallery galleryid-238427 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/1_mormantul_sfantului_lazar.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/1_mormantul_sfantului_lazar-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/2_intalnire_mitropoli_kition.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/2_intalnire_mitropoli_kition-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/3_fotografie_grup_mitropolit_kition.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/3_fotografie_grup_mitropolit_kition-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/4_turle_cruci_mitropolie_tamassos.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/4_turle_cruci_mitropolie_tamassos-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/5_discutii_mitropolie_tamassos.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/5_discutii_mitropolie_tamassos-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/7_grup_mitropolit_isaia_explicatii.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/7_grup_mitropolit_isaia_explicatii-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/6_mitropolitul_isaia_tamassos_fotografiat.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/6_mitropolitul_isaia_tamassos_fotografiat-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/Orthodox-media-representatives-with-Metropolitan-of-Limassol.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/Orthodox-media-representatives-with-Metropolitan-of-Limassol-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-238379\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-238379'>\n\t\t\t\tOrthodox media representatives from different countries met with Metropolitan of Limassol at his office. Photo: Orthphoto \/ Aleksander Wasyluk\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/8_interviu_mitropolit_limassol.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/8_interviu_mitropolit_limassol-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/13_atanasie_limassol.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/13_atanasie_limassol-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/13_atanasie_limassol_zambet.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/13_atanasie_limassol_zambet-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/15_sfanta_cruce.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/15_sfanta_cruce-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/9_binecuvantare_cruce_omodos.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/9_binecuvantare_cruce_omodos-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/10_vizita_oras_cipru.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/10_vizita_oras_cipru-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1600x1068' href='https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/11_intalnire_staret_machairas_epifanie.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/11_intalnire_staret_machairas_epifanie-360x360.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-238404\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-238404'>\n\t\t\t\tOrthodox media representatives from different countries met with the Abbot of Machairas Monastery, Bishop Epiphanius of Ledra. Photo: Orthphoto \/ Aleksander Wasyluk\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Photography courtesy of OrthPhoto \/ Aleksander Wasyluk<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Different representatives of Orthodox media outlets gathered in Cyprus from May 15 to May 19, 2019, to find ways of strengthening the international cooperation between Orthodox media specialists. The meeting was occasioned by the opening of the \u2018Colours of Orthodoxy. Cyprus &#8211; Poland\u2019 Exhibition organized by the OrthPhoto.net photography website, the Archdiocese of Cyprus, the&hellip;<\/p>\n","protected":false},"author":3,"featured_media":238396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[19421,19420,10386,18999,15620],"class_list":["post-238427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international","tag-international-cooperation","tag-orthodox-media","tag-orthodox-news","tag-orthphoto-en","tag-stiri-ortodoxe-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Orthodox media representatives meet in Cyprus to strengthen international cooperation - Basilica.ro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orthodox media representatives meet in Cyprus to strengthen international cooperation\" \/>\n<meta property=\"og:description\" content=\"Different representatives of Orthodox media outlets gathered in Cyprus from May 15 to May 19, 2019, to find ways of strengthening the international\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/\" \/>\n<meta property=\"og:site_name\" content=\"Basilica.ro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basilica.ro\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-20T20:18:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-21T04:41:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/7_grup_mitropolit_isaia_explicatii.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aurelian Iftimiu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AurelianNicolae\" \/>\n<meta name=\"twitter:site\" content=\"@AgentiaBasilica\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/\"},\"author\":{\"name\":\"Aurelian Iftimiu\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/person\\\/3b10696f83f62d60741521aedbcbb8d1\"},\"headline\":\"Orthodox media representatives meet in Cyprus to strengthen international cooperation\",\"datePublished\":\"2019-05-20T20:18:42+00:00\",\"dateModified\":\"2019-05-21T04:41:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/\"},\"wordCount\":365,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/7_grup_mitropolit_isaia_explicatii.jpeg\",\"keywords\":[\"international cooperation\",\"Orthodox media\",\"Orthodox news\",\"OrthPhoto\",\"\u015ftiri ortodoxe\"],\"articleSection\":[\"International\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/\",\"name\":\"Orthodox media representatives meet in Cyprus to strengthen international cooperation - Basilica.ro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/7_grup_mitropolit_isaia_explicatii.jpeg\",\"datePublished\":\"2019-05-20T20:18:42+00:00\",\"dateModified\":\"2019-05-21T04:41:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/7_grup_mitropolit_isaia_explicatii.jpeg\",\"contentUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/7_grup_mitropolit_isaia_explicatii.jpeg\",\"width\":1600,\"height\":1068},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"International\",\"item\":\"https:\\\/\\\/basilica.ro\\\/en\\\/category\\\/international\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Orthodox media representatives meet in Cyprus to strengthen international cooperation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\",\"name\":\"Basilica.ro\",\"description\":\"Basilica News Agency of the Romanian Patriarchate\",\"publisher\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/basilica.ro\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#organization\",\"name\":\"Agen\u021bia de \u0219tiri Basilica\",\"alternateName\":\"Basilica.ro\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-basilica.jpg\",\"contentUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-basilica.jpg\",\"width\":1680,\"height\":945,\"caption\":\"Agen\u021bia de \u0219tiri Basilica\"},\"image\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/basilica.ro\\\/\",\"https:\\\/\\\/x.com\\\/AgentiaBasilica\",\"https:\\\/\\\/www.instagram.com\\\/basilica.ro\\\/\",\"https:\\\/\\\/ro.pinterest.com\\\/basilicaro\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCh6MZX0N9faHq70F4kBDBeA\",\"https:\\\/\\\/ro.wikipedia.org\\\/wiki\\\/Agen\u021bia_de_\u0219tiri_BASILICA\",\"https:\\\/\\\/www.facebook.com\\\/basilica.en\",\"https:\\\/\\\/x.com\\\/basilicanews\",\"https:\\\/\\\/x.com\\\/basilicaphotos\"],\"description\":\"Agen\u021bia de \u0219tiri Basilica este canalul oficial de informare al Bisericii Ortodoxe Rom\u00e2ne (Patriarhia Rom\u00e2n\u0103)\",\"email\":\"info@basilica.ro\",\"foundingDate\":\"2008-10-27\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/person\\\/3b10696f83f62d60741521aedbcbb8d1\",\"name\":\"Aurelian Iftimiu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g\",\"caption\":\"Aurelian Iftimiu\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AurelianNicolae\"],\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/author\\\/aurelian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Orthodox media representatives meet in Cyprus to strengthen international cooperation - Basilica.ro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/","og_locale":"en_US","og_type":"article","og_title":"Orthodox media representatives meet in Cyprus to strengthen international cooperation","og_description":"Different representatives of Orthodox media outlets gathered in Cyprus from May 15 to May 19, 2019, to find ways of strengthening the international","og_url":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/","og_site_name":"Basilica.ro","article_publisher":"https:\/\/www.facebook.com\/basilica.ro\/","article_published_time":"2019-05-20T20:18:42+00:00","article_modified_time":"2019-05-21T04:41:20+00:00","og_image":[{"width":1600,"height":1068,"url":"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/7_grup_mitropolit_isaia_explicatii.jpeg","type":"image\/jpeg"}],"author":"Aurelian Iftimiu","twitter_card":"summary_large_image","twitter_creator":"@AurelianNicolae","twitter_site":"@AgentiaBasilica","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/#article","isPartOf":{"@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/"},"author":{"name":"Aurelian Iftimiu","@id":"https:\/\/basilica.ro\/en\/#\/schema\/person\/3b10696f83f62d60741521aedbcbb8d1"},"headline":"Orthodox media representatives meet in Cyprus to strengthen international cooperation","datePublished":"2019-05-20T20:18:42+00:00","dateModified":"2019-05-21T04:41:20+00:00","mainEntityOfPage":{"@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/"},"wordCount":365,"commentCount":0,"publisher":{"@id":"https:\/\/basilica.ro\/en\/#organization"},"image":{"@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/#primaryimage"},"thumbnailUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/7_grup_mitropolit_isaia_explicatii.jpeg","keywords":["international cooperation","Orthodox media","Orthodox news","OrthPhoto","\u015ftiri ortodoxe"],"articleSection":["International"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/","url":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/","name":"Orthodox media representatives meet in Cyprus to strengthen international cooperation - Basilica.ro","isPartOf":{"@id":"https:\/\/basilica.ro\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/#primaryimage"},"image":{"@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/#primaryimage"},"thumbnailUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/7_grup_mitropolit_isaia_explicatii.jpeg","datePublished":"2019-05-20T20:18:42+00:00","dateModified":"2019-05-21T04:41:20+00:00","breadcrumb":{"@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/#primaryimage","url":"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/7_grup_mitropolit_isaia_explicatii.jpeg","contentUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2019\/05\/7_grup_mitropolit_isaia_explicatii.jpeg","width":1600,"height":1068},{"@type":"BreadcrumbList","@id":"https:\/\/basilica.ro\/en\/orthodox-media-representatives-meet-in-cyprus-to-strengthen-international-cooperation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/basilica.ro\/en\/"},{"@type":"ListItem","position":2,"name":"International","item":"https:\/\/basilica.ro\/en\/category\/international\/"},{"@type":"ListItem","position":3,"name":"Orthodox media representatives meet in Cyprus to strengthen international cooperation"}]},{"@type":"WebSite","@id":"https:\/\/basilica.ro\/en\/#website","url":"https:\/\/basilica.ro\/en\/","name":"Basilica.ro","description":"Basilica News Agency of the Romanian Patriarchate","publisher":{"@id":"https:\/\/basilica.ro\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basilica.ro\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/basilica.ro\/en\/#organization","name":"Agen\u021bia de \u0219tiri Basilica","alternateName":"Basilica.ro","url":"https:\/\/basilica.ro\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basilica.ro\/en\/#\/schema\/logo\/image\/","url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/06\/logo-basilica.jpg","contentUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/06\/logo-basilica.jpg","width":1680,"height":945,"caption":"Agen\u021bia de \u0219tiri Basilica"},"image":{"@id":"https:\/\/basilica.ro\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/basilica.ro\/","https:\/\/x.com\/AgentiaBasilica","https:\/\/www.instagram.com\/basilica.ro\/","https:\/\/ro.pinterest.com\/basilicaro\/","https:\/\/www.youtube.com\/channel\/UCh6MZX0N9faHq70F4kBDBeA","https:\/\/ro.wikipedia.org\/wiki\/Agen\u021bia_de_\u0219tiri_BASILICA","https:\/\/www.facebook.com\/basilica.en","https:\/\/x.com\/basilicanews","https:\/\/x.com\/basilicaphotos"],"description":"Agen\u021bia de \u0219tiri Basilica este canalul oficial de informare al Bisericii Ortodoxe Rom\u00e2ne (Patriarhia Rom\u00e2n\u0103)","email":"info@basilica.ro","foundingDate":"2008-10-27","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/basilica.ro\/en\/#\/schema\/person\/3b10696f83f62d60741521aedbcbb8d1","name":"Aurelian Iftimiu","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g","caption":"Aurelian Iftimiu"},"sameAs":["https:\/\/x.com\/AurelianNicolae"],"url":"https:\/\/basilica.ro\/en\/author\/aurelian\/"}]}},"_links":{"self":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/posts\/238427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/comments?post=238427"}],"version-history":[{"count":0,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/posts\/238427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/media\/238396"}],"wp:attachment":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/media?parent=238427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/categories?post=238427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/tags?post=238427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}