{"id":216918,"date":"2018-11-23T16:30:18","date_gmt":"2018-11-23T14:30:18","guid":{"rendered":"http:\/\/basilica.ro\/?p=216918"},"modified":"2018-11-23T17:34:22","modified_gmt":"2018-11-23T15:34:22","slug":"welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery","status":"publish","type":"post","link":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/","title":{"rendered":"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery"},"content":{"rendered":"<p><strong>An <a href=\"http:\/\/basilica.ro\/en\/ecumenical-patriarch-officially-welcomed-by-patriarch-daniel-at-the-patriarchal-cathedral-in-bucharest-video\/\">official welcome ceremony<\/a> was held Friday, November 23, 208, at the Patriarchal Cathedral in Bucharest for Ecumenical Patriarch Bartholomew who will lead the inauguration of Romania&#8217;s National Cathedral this Sunday.<\/strong><\/p>\n<div id='gallery-1' class='gallery galleryid-216918 gallery-columns-6 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-100.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-100.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-100.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-100-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-100-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-101.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-101.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-101.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-101-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-101-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-102.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-102.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-102.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-102-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-102-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-103.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-103.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-103.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-103-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-103-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-104.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-104.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-104.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-104-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-104-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-105.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-105.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-105.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-105-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-105-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-107.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-107.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-107.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-107-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-107-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-108.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-108.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-108.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-108-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-108-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-size='1267x1900' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-109.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1267\" height=\"1900\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-109.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-109.jpg 1267w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-109-593x890.jpg 593w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-109-683x1024.jpg 683w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-110.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-110.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-110.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-110-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-110-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-size='1267x1900' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-111.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1267\" height=\"1900\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-111.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-111.jpg 1267w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-111-593x890.jpg 593w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-111-683x1024.jpg 683w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-112.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-112.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-112.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-112-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-112-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-113.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-113.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-113.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-113-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-113-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-114.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-114.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-114.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-114-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-114-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-116.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-116.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-116.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-116-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-116-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-117.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-117.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-117.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-117-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-117-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-118.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-118.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-118.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-118-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-118-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-119.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-119.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-119.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-119-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-119-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-120.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-120.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-120.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-120-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-120-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-121.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-121.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-121.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-121-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-121-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-122.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-122.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-122.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-122-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-122-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-123.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-123.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-123.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-123-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-123-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-124.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-124.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-124.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-124-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-124-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-125.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-125.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-125.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-125-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-125-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-126.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-126.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-126.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-126-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-126-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-127.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-127.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-127.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-127-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-127-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-128.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-128.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-128.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-128-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-128-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-129.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-129.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-129.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-129-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-129-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-130.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-130.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-130.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-130-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-130-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-131.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-131.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-131.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-131-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-131-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-132.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-132.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-132.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-132-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-132-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-133.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-133.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-133.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-133-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-133-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-134.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-134.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-134.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-134-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-134-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-135.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-135.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-135.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-135-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-135-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-size='1900x1267' href='https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-136.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"1267\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-136.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-136.jpg 1900w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-136-890x593.jpg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-136-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Photography courtesy of Mircea Florescu \/ <strong>Basilica.ro<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>An official welcome ceremony was held Friday, November 23, 208, at the Patriarchal Cathedral in Bucharest for Ecumenical Patriarch Bartholomew who will lead the inauguration of Romania&#8217;s National Cathedral this Sunday. Photography courtesy of Mircea Florescu \/ Basilica.ro<\/p>\n","protected":false},"author":3,"featured_media":216865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[878],"tags":[16433,67,16389,886,8658,4463,17737],"class_list":["post-216918","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-photo-galleries","tag-catedrala-mantuirii-neamului-en","tag-ecumenical-patriarch","tag-in-pictures","tag-national-cathedral","tag-photo-gallery","tag-romanian-peoples-salvation-cathedral","tag-welcome-ceremony","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery - Basilica.ro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery\" \/>\n<meta property=\"og:description\" content=\"An official welcome ceremony was held Friday, November 23, 208, at the Patriarchal Cathedral in Bucharest for Ecumenical Patriarch Bartholomew who will\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"Basilica.ro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basilica.ro\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-23T14:30:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-23T15:34:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aurelian Iftimiu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AurelianNicolae\" \/>\n<meta name=\"twitter:site\" content=\"@AgentiaBasilica\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/\"},\"author\":{\"name\":\"Aurelian Iftimiu\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/person\\\/3b10696f83f62d60741521aedbcbb8d1\"},\"headline\":\"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery\",\"datePublished\":\"2018-11-23T14:30:18+00:00\",\"dateModified\":\"2018-11-23T15:34:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/\"},\"wordCount\":54,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Primire-Moaste-Sf-Andrei-115.jpg\",\"keywords\":[\"Catedrala M\u00e2ntuirii Neamului\",\"Ecumenical Patriarch\",\"in pictures\",\"National cathedral\",\"photo gallery\",\"Romanian People's Salvation Cathedral\",\"welcome ceremony\"],\"articleSection\":[\"Photo Galleries\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/\",\"name\":\"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery - Basilica.ro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Primire-Moaste-Sf-Andrei-115.jpg\",\"datePublished\":\"2018-11-23T14:30:18+00:00\",\"dateModified\":\"2018-11-23T15:34:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/#primaryimage\",\"url\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Primire-Moaste-Sf-Andrei-115.jpg\",\"contentUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Primire-Moaste-Sf-Andrei-115.jpg\",\"width\":1900,\"height\":1267},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photo Galleries\",\"item\":\"https:\\\/\\\/basilica.ro\\\/en\\\/category\\\/photo-galleries\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\",\"name\":\"Basilica.ro\",\"description\":\"Basilica News Agency of the Romanian Patriarchate\",\"publisher\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/basilica.ro\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#organization\",\"name\":\"Agen\u021bia de \u0219tiri Basilica\",\"alternateName\":\"Basilica.ro\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-basilica.jpg\",\"contentUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-basilica.jpg\",\"width\":1680,\"height\":945,\"caption\":\"Agen\u021bia de \u0219tiri Basilica\"},\"image\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/basilica.ro\\\/\",\"https:\\\/\\\/x.com\\\/AgentiaBasilica\",\"https:\\\/\\\/www.instagram.com\\\/basilica.ro\\\/\",\"https:\\\/\\\/ro.pinterest.com\\\/basilicaro\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCh6MZX0N9faHq70F4kBDBeA\",\"https:\\\/\\\/ro.wikipedia.org\\\/wiki\\\/Agen\u021bia_de_\u0219tiri_BASILICA\",\"https:\\\/\\\/www.facebook.com\\\/basilica.en\",\"https:\\\/\\\/x.com\\\/basilicanews\",\"https:\\\/\\\/x.com\\\/basilicaphotos\"],\"description\":\"Agen\u021bia de \u0219tiri Basilica este canalul oficial de informare al Bisericii Ortodoxe Rom\u00e2ne (Patriarhia Rom\u00e2n\u0103)\",\"email\":\"info@basilica.ro\",\"foundingDate\":\"2008-10-27\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/person\\\/3b10696f83f62d60741521aedbcbb8d1\",\"name\":\"Aurelian Iftimiu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g\",\"caption\":\"Aurelian Iftimiu\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AurelianNicolae\"],\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/author\\\/aurelian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery - Basilica.ro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/","og_locale":"en_US","og_type":"article","og_title":"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery","og_description":"An official welcome ceremony was held Friday, November 23, 208, at the Patriarchal Cathedral in Bucharest for Ecumenical Patriarch Bartholomew who will","og_url":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/","og_site_name":"Basilica.ro","article_publisher":"https:\/\/www.facebook.com\/basilica.ro\/","article_published_time":"2018-11-23T14:30:18+00:00","article_modified_time":"2018-11-23T15:34:22+00:00","og_image":[{"width":1900,"height":1267,"url":"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg","type":"image\/jpeg"}],"author":"Aurelian Iftimiu","twitter_card":"summary_large_image","twitter_creator":"@AurelianNicolae","twitter_site":"@AgentiaBasilica","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/#article","isPartOf":{"@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/"},"author":{"name":"Aurelian Iftimiu","@id":"https:\/\/basilica.ro\/en\/#\/schema\/person\/3b10696f83f62d60741521aedbcbb8d1"},"headline":"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery","datePublished":"2018-11-23T14:30:18+00:00","dateModified":"2018-11-23T15:34:22+00:00","mainEntityOfPage":{"@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/"},"wordCount":54,"commentCount":0,"publisher":{"@id":"https:\/\/basilica.ro\/en\/#organization"},"image":{"@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/#primaryimage"},"thumbnailUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg","keywords":["Catedrala M\u00e2ntuirii Neamului","Ecumenical Patriarch","in pictures","National cathedral","photo gallery","Romanian People's Salvation Cathedral","welcome ceremony"],"articleSection":["Photo Galleries"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/","url":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/","name":"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery - Basilica.ro","isPartOf":{"@id":"https:\/\/basilica.ro\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/#primaryimage"},"image":{"@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/#primaryimage"},"thumbnailUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg","datePublished":"2018-11-23T14:30:18+00:00","dateModified":"2018-11-23T15:34:22+00:00","breadcrumb":{"@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/#primaryimage","url":"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg","contentUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2018\/11\/Primire-Moaste-Sf-Andrei-115.jpg","width":1900,"height":1267},{"@type":"BreadcrumbList","@id":"https:\/\/basilica.ro\/en\/welcoming-ceremony-for-ecumenical-patriarch-bartholomew-in-bucharest-photo-gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/basilica.ro\/en\/"},{"@type":"ListItem","position":2,"name":"Photo Galleries","item":"https:\/\/basilica.ro\/en\/category\/photo-galleries\/"},{"@type":"ListItem","position":3,"name":"Welcoming ceremony for Ecumenical Patriarch Bartholomew in Bucharest: Photo Gallery"}]},{"@type":"WebSite","@id":"https:\/\/basilica.ro\/en\/#website","url":"https:\/\/basilica.ro\/en\/","name":"Basilica.ro","description":"Basilica News Agency of the Romanian Patriarchate","publisher":{"@id":"https:\/\/basilica.ro\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basilica.ro\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/basilica.ro\/en\/#organization","name":"Agen\u021bia de \u0219tiri Basilica","alternateName":"Basilica.ro","url":"https:\/\/basilica.ro\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basilica.ro\/en\/#\/schema\/logo\/image\/","url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/06\/logo-basilica.jpg","contentUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/06\/logo-basilica.jpg","width":1680,"height":945,"caption":"Agen\u021bia de \u0219tiri Basilica"},"image":{"@id":"https:\/\/basilica.ro\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/basilica.ro\/","https:\/\/x.com\/AgentiaBasilica","https:\/\/www.instagram.com\/basilica.ro\/","https:\/\/ro.pinterest.com\/basilicaro\/","https:\/\/www.youtube.com\/channel\/UCh6MZX0N9faHq70F4kBDBeA","https:\/\/ro.wikipedia.org\/wiki\/Agen\u021bia_de_\u0219tiri_BASILICA","https:\/\/www.facebook.com\/basilica.en","https:\/\/x.com\/basilicanews","https:\/\/x.com\/basilicaphotos"],"description":"Agen\u021bia de \u0219tiri Basilica este canalul oficial de informare al Bisericii Ortodoxe Rom\u00e2ne (Patriarhia Rom\u00e2n\u0103)","email":"info@basilica.ro","foundingDate":"2008-10-27","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/basilica.ro\/en\/#\/schema\/person\/3b10696f83f62d60741521aedbcbb8d1","name":"Aurelian Iftimiu","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48062afd75c6825bfa6e875a1a09ccf5a3a2b0b3eb31a03a35a0ec045884f8a5?s=96&d=mm&r=g","caption":"Aurelian Iftimiu"},"sameAs":["https:\/\/x.com\/AurelianNicolae"],"url":"https:\/\/basilica.ro\/en\/author\/aurelian\/"}]}},"_links":{"self":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/posts\/216918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/comments?post=216918"}],"version-history":[{"count":0,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/posts\/216918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/media\/216865"}],"wp:attachment":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/media?parent=216918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/categories?post=216918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/tags?post=216918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}