{"id":287339,"date":"2020-07-30T15:56:40","date_gmt":"2020-07-30T12:56:40","guid":{"rendered":"http:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31.jpeg"},"modified":"2020-08-05T17:48:28","modified_gmt":"2020-08-05T14:48:28","slug":"whatsapp-image-2020-07-30-at-15-51-31-2","status":"inherit","type":"attachment","link":"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/","title":{"rendered":"WhatsApp Image 2020-07-30 at 15.51.31"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-287339","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>WhatsApp Image 2020-07-30 at 15.51.31 - Basilica.ro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WhatsApp Image 2020-07-30 at 15.51.31\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Basilica.ro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/basilica.ro\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-05T14:48:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AgentiaBasilica\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/the-dormition-fast-resources\\\/whatsapp-image-2020-07-30-at-15-51-31-2\\\/\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/the-dormition-fast-resources\\\/whatsapp-image-2020-07-30-at-15-51-31-2\\\/\",\"name\":\"WhatsApp Image 2020-07-30 at 15.51.31 - Basilica.ro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#website\"},\"datePublished\":\"2020-07-30T12:56:40+00:00\",\"dateModified\":\"2020-08-05T14:48:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/the-dormition-fast-resources\\\/whatsapp-image-2020-07-30-at-15-51-31-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/basilica.ro\\\/en\\\/the-dormition-fast-resources\\\/whatsapp-image-2020-07-30-at-15-51-31-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/the-dormition-fast-resources\\\/whatsapp-image-2020-07-30-at-15-51-31-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spirituality\",\"item\":\"https:\\\/\\\/basilica.ro\\\/en\\\/category\\\/spirituality-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Dormition Fast | Resources\",\"item\":\"https:\\\/\\\/basilica.ro\\\/en\\\/the-dormition-fast-resources\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"WhatsApp Image 2020-07-30 at 15.51.31\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\",\"name\":\"Basilica.ro\",\"description\":\"Basilica News Agency of the Romanian Patriarchate\",\"publisher\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/basilica.ro\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#organization\",\"name\":\"Agen\u021bia de \u0219tiri Basilica\",\"alternateName\":\"Basilica.ro\",\"url\":\"https:\\\/\\\/basilica.ro\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-basilica.jpg\",\"contentUrl\":\"https:\\\/\\\/basilica.ro\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-basilica.jpg\",\"width\":1680,\"height\":945,\"caption\":\"Agen\u021bia de \u0219tiri Basilica\"},\"image\":{\"@id\":\"https:\\\/\\\/basilica.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/basilica.ro\\\/\",\"https:\\\/\\\/x.com\\\/AgentiaBasilica\",\"https:\\\/\\\/www.instagram.com\\\/basilica.ro\\\/\",\"https:\\\/\\\/ro.pinterest.com\\\/basilicaro\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCh6MZX0N9faHq70F4kBDBeA\",\"https:\\\/\\\/ro.wikipedia.org\\\/wiki\\\/Agen\u021bia_de_\u0219tiri_BASILICA\",\"https:\\\/\\\/www.facebook.com\\\/basilica.en\",\"https:\\\/\\\/x.com\\\/basilicanews\",\"https:\\\/\\\/x.com\\\/basilicaphotos\"],\"description\":\"Agen\u021bia de \u0219tiri Basilica este canalul oficial de informare al Bisericii Ortodoxe Rom\u00e2ne (Patriarhia Rom\u00e2n\u0103)\",\"email\":\"info@basilica.ro\",\"foundingDate\":\"2008-10-27\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"WhatsApp Image 2020-07-30 at 15.51.31 - Basilica.ro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/","og_locale":"en_US","og_type":"article","og_title":"WhatsApp Image 2020-07-30 at 15.51.31","og_url":"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/","og_site_name":"Basilica.ro","article_publisher":"https:\/\/www.facebook.com\/basilica.ro\/","article_modified_time":"2020-08-05T14:48:28+00:00","og_image":[{"width":1600,"height":1434,"url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AgentiaBasilica","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/","url":"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/","name":"WhatsApp Image 2020-07-30 at 15.51.31 - Basilica.ro","isPartOf":{"@id":"https:\/\/basilica.ro\/en\/#website"},"datePublished":"2020-07-30T12:56:40+00:00","dateModified":"2020-08-05T14:48:28+00:00","breadcrumb":{"@id":"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/whatsapp-image-2020-07-30-at-15-51-31-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/basilica.ro\/en\/"},{"@type":"ListItem","position":2,"name":"Spirituality","item":"https:\/\/basilica.ro\/en\/category\/spirituality-en\/"},{"@type":"ListItem","position":3,"name":"The Dormition Fast | Resources","item":"https:\/\/basilica.ro\/en\/the-dormition-fast-resources\/"},{"@type":"ListItem","position":4,"name":"WhatsApp Image 2020-07-30 at 15.51.31"}]},{"@type":"WebSite","@id":"https:\/\/basilica.ro\/en\/#website","url":"https:\/\/basilica.ro\/en\/","name":"Basilica.ro","description":"Basilica News Agency of the Romanian Patriarchate","publisher":{"@id":"https:\/\/basilica.ro\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basilica.ro\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/basilica.ro\/en\/#organization","name":"Agen\u021bia de \u0219tiri Basilica","alternateName":"Basilica.ro","url":"https:\/\/basilica.ro\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/basilica.ro\/en\/#\/schema\/logo\/image\/","url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/06\/logo-basilica.jpg","contentUrl":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/06\/logo-basilica.jpg","width":1680,"height":945,"caption":"Agen\u021bia de \u0219tiri Basilica"},"image":{"@id":"https:\/\/basilica.ro\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/basilica.ro\/","https:\/\/x.com\/AgentiaBasilica","https:\/\/www.instagram.com\/basilica.ro\/","https:\/\/ro.pinterest.com\/basilicaro\/","https:\/\/www.youtube.com\/channel\/UCh6MZX0N9faHq70F4kBDBeA","https:\/\/ro.wikipedia.org\/wiki\/Agen\u021bia_de_\u0219tiri_BASILICA","https:\/\/www.facebook.com\/basilica.en","https:\/\/x.com\/basilicanews","https:\/\/x.com\/basilicaphotos"],"description":"Agen\u021bia de \u0219tiri Basilica este canalul oficial de informare al Bisericii Ortodoxe Rom\u00e2ne (Patriarhia Rom\u00e2n\u0103)","email":"info@basilica.ro","foundingDate":"2008-10-27","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"description":{"rendered":"<p class=\"attachment\"><a data-size='1600x1434' href='https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"890\" height=\"798\" src=\"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31-890x798.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31-890x798.jpeg 890w, https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31-1024x918.jpeg 1024w, https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31-1536x1377.jpeg 1536w, https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31.jpeg 1600w\" sizes=\"auto, (max-width: 480px) 440px, (max-width: 768px) 354px, 890px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1434,"file":"2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31.jpeg","sizes":{"medium":{"file":"WhatsApp-Image-2020-07-30-at-15.51.31-890x798.jpeg","width":890,"height":798,"mime_type":"image\/jpeg","source_url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31-890x798.jpeg"},"large":{"file":"WhatsApp-Image-2020-07-30-at-15.51.31-1024x918.jpeg","width":1024,"height":918,"mime_type":"image\/jpeg","source_url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31-1024x918.jpeg"},"thumbnail":{"file":"WhatsApp-Image-2020-07-30-at-15.51.31-360x360.jpeg","width":360,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31-360x360.jpeg"},"1536x1536":{"file":"WhatsApp-Image-2020-07-30-at-15.51.31-1536x1377.jpeg","width":1536,"height":1377,"mime_type":"image\/jpeg","source_url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31-1536x1377.jpeg"},"full":{"file":"WhatsApp-Image-2020-07-30-at-15.51.31.jpeg","width":1600,"height":1434,"mime_type":"image\/jpeg","source_url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":287792,"source_url":"https:\/\/basilica.ro\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-07-30-at-15.51.31.jpeg","filename":"WhatsApp-Image-2020-07-30-at-15.51.31.jpeg","filesize":138093,"_links":{"self":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/media\/287339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/comments?post=287339"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":287792,"href":"https:\/\/basilica.ro\/en\/wp-json\/wp\/v2\/posts\/287792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}